{"id":4620,"date":"2026-07-14T19:14:59","date_gmt":"2026-07-14T19:14:59","guid":{"rendered":"https:\/\/camaraguaranesia.mg.gov.br\/site\/?p=4620"},"modified":"2026-07-14T19:14:59","modified_gmt":"2026-07-14T19:14:59","slug":"credenciamento-cartao-vale-alimentacao","status":"publish","type":"post","link":"https:\/\/camaraguaranesia.mg.gov.br\/site\/credenciamento-cartao-vale-alimentacao\/","title":{"rendered":"Credenciamento Cart\u00e3o Vale Alimenta\u00e7\u00e3o"},"content":{"rendered":"<p>C\u00e2mara Municipal de Guaran\u00e9sia<br \/>\nModalidade: Credenciamento<br \/>\nN\u00ba Processo: 17\/2026<br \/>\nObjeto: Credenciamento para presta\u00e7\u00e3o de servi\u00e7os de gerenciamento, fornecimento e administra\u00e7\u00e3o do benef\u00edcio de aux\u00edlio-alimenta\u00e7\u00e3o aos servidores p\u00fablicos municipais, mediante cr\u00e9dito financeiro, na modalidade de arranjo aberto e fechado, com disponibiliza\u00e7\u00e3o de cart\u00e3o de alimenta\u00e7\u00e3o com chip e solu\u00e7\u00e3o digital (aplicativo), para utiliza\u00e7\u00e3o exclusiva junto \u00e0 rede credenciada para aquisi\u00e7\u00e3o de g\u00eaneros aliment\u00edcios. Confira abaixo a documenta\u00e7\u00e3o:<\/p>\n<p>01 &#8211; <a href=\"https:\/\/camaraguaranesia.mg.gov.br\/site\/wp-content\/uploads\/2026\/07\/Edital-Credenciamento-Vale-Alimentac\u0327a\u0303o.pdf\">Edital Credenciamento Vale-Alimentac\u0327a\u0303o<\/a><\/p>\n<p>02 &#8211; <a href=\"https:\/\/camaraguaranesia.mg.gov.br\/site\/wp-content\/uploads\/2026\/07\/Termo-de-Refere\u0302ncia-Anexo-I.pdf\">Termo de Refere\u0302ncia (Anexo I)<\/a><\/p>\n<p>03 &#8211; <a href=\"https:\/\/camaraguaranesia.mg.gov.br\/site\/wp-content\/uploads\/2026\/07\/Requerimento-Credenciamento-Anexo-II.pdf\">Requerimento Credenciamento (Anexo II)<\/a><\/p>\n<p>04 &#8211; <a href=\"https:\/\/camaraguaranesia.mg.gov.br\/site\/wp-content\/uploads\/2026\/07\/Declarac\u0327a\u0303o-Anexo-III.pdf\">Declarac\u0327a\u0303o (Anexo III)<\/a><\/p>\n<p>05 &#8211; <a href=\"https:\/\/camaraguaranesia.mg.gov.br\/site\/wp-content\/uploads\/2026\/07\/Termo-de-Credenciamento-Anexo-IV.pdf\">Termo de Credenciamento (Anexo IV)<\/a><\/p>\n<p>06 &#8211;\u00a0<a href=\"https:\/\/camaraguaranesia.mg.gov.br\/site\/wp-content\/uploads\/2026\/07\/Minuta-Contrato-Anexo-V-1.pdf\">Minuta Contrato (Anexo V) (1)<\/a><\/p>\n<p>07 &#8211;\u00a0<a href=\"https:\/\/camaraguaranesia.mg.gov.br\/site\/wp-content\/uploads\/2026\/07\/Decreto-relulamentac\u0327a\u0303o-federal-12712.pdf\">Decreto relulamentac\u0327a\u0303o federal 12712<\/a><\/p>\n<p>08 &#8211;\u00a0<a href=\"https:\/\/camaraguaranesia.mg.gov.br\/site\/wp-content\/uploads\/2026\/07\/LO-3.051-26-VALE-ALIMENTAC\u0327A\u0303O.pdf\">LO 3.051-26 VALE ALIMENTAC\u0327A\u0303O<\/a><\/p>\n<p>09 &#8211;\u00a0<a href=\"https:\/\/camaraguaranesia.mg.gov.br\/site\/wp-content\/uploads\/2026\/07\/ETP-2.pdf\">ETP (2)<\/a><\/p>\n<p>10 &#8211;\u00a0<a href=\"https:\/\/camaraguaranesia.mg.gov.br\/site\/wp-content\/uploads\/2026\/07\/DFD-CREDENCIAMENTO-3.pdf\">DFD CREDENCIAMENTO (3)<\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>C\u00e2mara Municipal de Guaran\u00e9sia Modalidade: Credenciamento N\u00ba Processo: 17\/2026 Objeto: Credenciamento para presta\u00e7\u00e3o de servi\u00e7os de gerenciamento, fornecimento e administra\u00e7\u00e3o do benef\u00edcio de aux\u00edlio-alimenta\u00e7\u00e3o aos servidores p\u00fablicos municipais, mediante cr\u00e9dito financeiro, na modalidade de arranjo aberto e fechado, com disponibiliza\u00e7\u00e3o de cart\u00e3o de alimenta\u00e7\u00e3o com chip e solu\u00e7\u00e3o digital (aplicativo), para utiliza\u00e7\u00e3o exclusiva junto \u00e0 &#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[27],"tags":[],"_links":{"self":[{"href":"https:\/\/camaraguaranesia.mg.gov.br\/site\/wp-json\/wp\/v2\/posts\/4620"}],"collection":[{"href":"https:\/\/camaraguaranesia.mg.gov.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/camaraguaranesia.mg.gov.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/camaraguaranesia.mg.gov.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/camaraguaranesia.mg.gov.br\/site\/wp-json\/wp\/v2\/comments?post=4620"}],"version-history":[{"count":1,"href":"https:\/\/camaraguaranesia.mg.gov.br\/site\/wp-json\/wp\/v2\/posts\/4620\/revisions"}],"predecessor-version":[{"id":4631,"href":"https:\/\/camaraguaranesia.mg.gov.br\/site\/wp-json\/wp\/v2\/posts\/4620\/revisions\/4631"}],"wp:attachment":[{"href":"https:\/\/camaraguaranesia.mg.gov.br\/site\/wp-json\/wp\/v2\/media?parent=4620"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/camaraguaranesia.mg.gov.br\/site\/wp-json\/wp\/v2\/categories?post=4620"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/camaraguaranesia.mg.gov.br\/site\/wp-json\/wp\/v2\/tags?post=4620"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}